{"id":8282,"date":"2023-05-25T14:11:03","date_gmt":"2023-05-25T14:11:03","guid":{"rendered":"https:\/\/ucie.ific.uv.es\/ucie\/?post_type=tribe_events&#038;p=8282"},"modified":"2023-05-25T14:11:03","modified_gmt":"2023-05-25T14:11:03","slug":"jornadas-anuales-de-promocion-del-programa-marco-europeo-de-idi","status":"publish","type":"tribe_events","link":"https:\/\/ucie.ific.uv.es\/ucie\/evento\/jornadas-anuales-de-promocion-del-programa-marco-europeo-de-idi\/","title":{"rendered":"Jornadas Anuales de Promoci\u00f3n del Programa Marco Europeo de I+D+I"},"content":{"rendered":"<p>Durante las jornadas se abordar\u00e1n\u00a0 las principales pol\u00edticas de la UE que hay que tener en cuenta para un adecuado enfoque de las propuestas as\u00ed como las novedades m\u00e1s destacadas sobre los topics y \u00e1reas de todos los cl\u00fasteres de Pilar II y una revisi\u00f3n de la EIC-Pathfinder, instrumento de financiaci\u00f3n de la innovaci\u00f3n de alto riesgo dentro de Pilar-III de HE. Se realizar\u00e1n tambi\u00e9n sendos talleres sobre los Planes de gesti\u00f3n de datos y sobre Informes de evaluaci\u00f3n de las propuestas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante las jornadas se abordar\u00e1n\u00a0 las principales pol\u00edticas de la UE que hay que tener en cuenta para un adecuado enfoque de las propuestas as\u00ed como las novedades m\u00e1s destacadas [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":8283,"comment_status":"open","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":""},"tags":[],"tribe_events_cat":[23],"acf":[],"_links":{"self":[{"href":"https:\/\/ucie.ific.uv.es\/ucie\/wp-json\/wp\/v2\/tribe_events\/8282"}],"collection":[{"href":"https:\/\/ucie.ific.uv.es\/ucie\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/ucie.ific.uv.es\/ucie\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/ucie.ific.uv.es\/ucie\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ucie.ific.uv.es\/ucie\/wp-json\/wp\/v2\/comments?post=8282"}],"version-history":[{"count":1,"href":"https:\/\/ucie.ific.uv.es\/ucie\/wp-json\/wp\/v2\/tribe_events\/8282\/revisions"}],"predecessor-version":[{"id":8284,"href":"https:\/\/ucie.ific.uv.es\/ucie\/wp-json\/wp\/v2\/tribe_events\/8282\/revisions\/8284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ucie.ific.uv.es\/ucie\/wp-json\/wp\/v2\/media\/8283"}],"wp:attachment":[{"href":"https:\/\/ucie.ific.uv.es\/ucie\/wp-json\/wp\/v2\/media?parent=8282"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ucie.ific.uv.es\/ucie\/wp-json\/wp\/v2\/tags?post=8282"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/ucie.ific.uv.es\/ucie\/wp-json\/wp\/v2\/tribe_events_cat?post=8282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}